{"id":5580,"date":"2014-02-09T12:27:29","date_gmt":"2014-02-09T10:27:29","guid":{"rendered":"http:\/\/bonnesadressesremoises.fr\/?p=5580"},"modified":"2016-02-16T12:22:01","modified_gmt":"2016-02-16T10:22:01","slug":"le-coq-rouge-reims","status":"publish","type":"post","link":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/","title":{"rendered":"Le Coq Rouge"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5594\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1.jpg\" alt=\"coq-rouge-1\" width=\"730\" height=\"320\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1.jpg 730w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1-500x219.jpg 500w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/p>\n<p>Le Coq Rouge existe depuis juillet 2012. Baptiste, avant de se lancer dans cette aventure, \u00e9tait sommelier pour de grands restaurants. Une envie de libert\u00e9 a souffl\u00e9 et surtout le d\u00e9sir de faire d\u00e9couvrir des vins singuliers. Ses choix s&rsquo;orientent vers ses go\u00fbts propres et il peut aussi bien int\u00e9grer dans sa partie caviste des vins de grands vignerons, issus de maisons de n\u00e9goce, mais surtout de jeunes vignerons talentueux.\u00a0\u00a0 <!--more--><\/p>\n<p>Vous pourrez ainsi d\u00e9couvrir ces vins soit chez vous (partie caviste) soit sur place (droit de bouchon) soit en d\u00e9gustant un verre de vin selon la s\u00e9lection du moment.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5595\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2.jpg\" alt=\"coq-rouge-2\" width=\"728\" height=\"407\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2.jpg 728w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2-500x279.jpg 500w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/p>\n<p>L&rsquo;endroit est petit et convivial. Si vous souhaitez y manger, il est pr\u00e9f\u00e9rable de r\u00e9server car le lieu est de fait rapidement complet. Vous sont propos\u00e9s le soir des planches de charcuteries tranch\u00e9es sur place, des sardines, en saison un Mont d&rsquo;Or, des mini-camemberts, des escargots.<\/p>\n<p>Vous pouvez aussi y venir \u00e0 tout moment boire un verre tout simplement. C&rsquo;est un lieu chaleureux o\u00f9 nous ne nous lassons pas d&rsquo;aller, les vins au verre changent tr\u00e8s r\u00e9guli\u00e8rement et les tarifs sont tr\u00e8s corrects, en coh\u00e9rence avec la partie caviste. Le choix est lui aussi important avec en moyenne un champagne \u00e0 la coupe, trois rouges, trois blancs et un ros\u00e9. Vous pouvez tout aussi bien partager une bouteille sur place en vous exon\u00e9rant d&rsquo;un droit de bouchon. Cela peut \u00eatre l&rsquo;occasion de vous offrir le magnum d&rsquo;un grand vin.<\/p>\n<p><span style=\"color: #ff6600;\"><strong>Edit : \u00ab\u00a0Le Coq Rouge\u00a0\u00bb cartonne ! Et il a fait un petit. Pas un petit poussin, mais une nouvelle adresse, qu&rsquo;on retrouve au 3 rue des Elus (tout pr\u00e8s de la place du Forum). C&rsquo;est la \u00ab\u00a0<\/strong><\/span><span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/bonnesadressesremoises.fr\/index.php\/cantine-du-coq\/\">Cantine du Coq<\/a><\/strong><\/span><span style=\"color: #ff6600;\"><strong>\u00a0\u00bb qui a ouvert en f\u00e9vrier 2015. Et c&rsquo;est top (<span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/bonnesadressesremoises.fr\/index.php\/cantine-du-coq\/\">cliquez<\/a><\/span> pour lire notre article) \ud83d\ude09\u00a0<\/strong><\/span><\/p>\n<table border=\"0\" bgcolor=\"#483737\">\n<tbody>\n<tr>\n<td>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><span style=\"color: #ffffff; text-decoration: underline; font-size: 70%;\">INFOS PRATIQUES<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff; font-variant: small-caps; font-size: 110%;\">Le Coq Rouge &#8211; 67 rue Chanzy &#8211; 51100 Reims<br \/>\n<\/span><a style=\"color: #ff6600;\" href=\"https:\/\/maps.google.fr\/maps?q=le+coq+rouge+reims&amp;ll=49.252691,4.033763&amp;spn=0.002852,0.004823&amp;t=h&amp;z=18&amp;iwloc=A\" target=\"_blank\">voir la localisation sur un plan<\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">t\u00e9l : 03.26.85.28.50<br \/>\nouvert du mardi au samedi de 16h \u00e0 00h30 (jusqu&rsquo;\u00e0 01h30 vendredi et samedi)<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5596\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3.jpg\" alt=\"coq-rouge-3\" width=\"730\" height=\"383\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3.jpg 730w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3-500x262.jpg 500w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-5580 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"96\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-6.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-6.jpg 715w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-6-319x300.jpg 319w\" sizes=\"auto, (max-width: 102px) 100vw, 102px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"82\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-5.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-5.jpg 730w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-5-469x300.jpg 469w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"67\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3.jpg 730w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-3-500x262.jpg 500w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"72\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2.jpg 728w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-2-500x279.jpg 500w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"96\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-4.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-4.jpg 394w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-4-188x300.jpg 188w\" sizes=\"auto, (max-width: 60px) 100vw, 60px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"56\" src=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1.jpg 730w, https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2014\/02\/coq-rouge-1-500x219.jpg 500w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Le Coq Rouge existe depuis juillet 2012. Baptiste, avant de se lancer dans cette aventure, \u00e9tait sommelier pour de grands restaurants. Une envie de libert\u00e9 a souffl\u00e9 et surtout le d\u00e9sir de faire d\u00e9couvrir des vins singuliers. Ses choix s&rsquo;orientent &hellip; <a href=\"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":9911,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-5580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pour-boire-un-verre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Coq Rouge # Bonnes Adresses R\u00e9moises<\/title>\n<meta name=\"description\" content=\"Caviste, bar \u00e0 manger, le Coq Rouge est un endroit convivial pour venir d\u00e9couvrir de bons vins. Situ\u00e9 rue Chanzy \u00e0 Reims. Ouvert du mardi au samedi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"bonnesadressesremoises.fr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/\"},\"author\":{\"name\":\"bonnesadressesremoises.fr\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#\\\/schema\\\/person\\\/23bf6fdaf1059471d3c6d236fdc5821e\"},\"headline\":\"Le Coq Rouge\",\"datePublished\":\"2014-02-09T10:27:29+00:00\",\"dateModified\":\"2016-02-16T10:22:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/\"},\"wordCount\":343,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pour-boire-un-verre.jpg\",\"articleSection\":[\"Pour boire un verre\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/\",\"url\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/\",\"name\":\"Le Coq Rouge # Bonnes Adresses R\u00e9moises\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pour-boire-un-verre.jpg\",\"datePublished\":\"2014-02-09T10:27:29+00:00\",\"dateModified\":\"2016-02-16T10:22:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#\\\/schema\\\/person\\\/23bf6fdaf1059471d3c6d236fdc5821e\"},\"description\":\"Caviste, bar \u00e0 manger, le Coq Rouge est un endroit convivial pour venir d\u00e9couvrir de bons vins. Situ\u00e9 rue Chanzy \u00e0 Reims. Ouvert du mardi au samedi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pour-boire-un-verre.jpg\",\"contentUrl\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pour-boire-un-verre.jpg\",\"width\":1000,\"height\":215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/le-coq-rouge-reims\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonnes Adresses\",\"item\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/category\\\/bonnes-adresses-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pour boire un verre\",\"item\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/category\\\/bonnes-adresses-2\\\/pour-boire-un-verre\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Le Coq Rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#website\",\"url\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/\",\"name\":\"Bonnes Adresses R\u00e9moises\",\"description\":\"Des bonnes adresses sur Reims!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#\\\/schema\\\/person\\\/23bf6fdaf1059471d3c6d236fdc5821e\",\"name\":\"bonnesadressesremoises.fr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Coq Rouge # Bonnes Adresses R\u00e9moises","description":"Caviste, bar \u00e0 manger, le Coq Rouge est un endroit convivial pour venir d\u00e9couvrir de bons vins. Situ\u00e9 rue Chanzy \u00e0 Reims. Ouvert du mardi au samedi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/","twitter_misc":{"\u00c9crit par":"bonnesadressesremoises.fr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#article","isPartOf":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/"},"author":{"name":"bonnesadressesremoises.fr","@id":"https:\/\/bonnesadressesremoises.fr\/#\/schema\/person\/23bf6fdaf1059471d3c6d236fdc5821e"},"headline":"Le Coq Rouge","datePublished":"2014-02-09T10:27:29+00:00","dateModified":"2016-02-16T10:22:01+00:00","mainEntityOfPage":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/"},"wordCount":343,"commentCount":1,"image":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#primaryimage"},"thumbnailUrl":"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2015\/11\/pour-boire-un-verre.jpg","articleSection":["Pour boire un verre"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/","url":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/","name":"Le Coq Rouge # Bonnes Adresses R\u00e9moises","isPartOf":{"@id":"https:\/\/bonnesadressesremoises.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#primaryimage"},"image":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#primaryimage"},"thumbnailUrl":"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2015\/11\/pour-boire-un-verre.jpg","datePublished":"2014-02-09T10:27:29+00:00","dateModified":"2016-02-16T10:22:01+00:00","author":{"@id":"https:\/\/bonnesadressesremoises.fr\/#\/schema\/person\/23bf6fdaf1059471d3c6d236fdc5821e"},"description":"Caviste, bar \u00e0 manger, le Coq Rouge est un endroit convivial pour venir d\u00e9couvrir de bons vins. Situ\u00e9 rue Chanzy \u00e0 Reims. Ouvert du mardi au samedi.","breadcrumb":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#primaryimage","url":"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2015\/11\/pour-boire-un-verre.jpg","contentUrl":"https:\/\/bonnesadressesremoises.fr\/wp-content\/uploads\/2015\/11\/pour-boire-un-verre.jpg","width":1000,"height":215},{"@type":"BreadcrumbList","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/le-coq-rouge-reims\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bonnesadressesremoises.fr\/"},{"@type":"ListItem","position":2,"name":"Bonnes Adresses","item":"https:\/\/bonnesadressesremoises.fr\/index.php\/category\/bonnes-adresses-2\/"},{"@type":"ListItem","position":3,"name":"Pour boire un verre","item":"https:\/\/bonnesadressesremoises.fr\/index.php\/category\/bonnes-adresses-2\/pour-boire-un-verre\/"},{"@type":"ListItem","position":4,"name":"Le Coq Rouge"}]},{"@type":"WebSite","@id":"https:\/\/bonnesadressesremoises.fr\/#website","url":"https:\/\/bonnesadressesremoises.fr\/","name":"Bonnes Adresses R\u00e9moises","description":"Des bonnes adresses sur Reims!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonnesadressesremoises.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/bonnesadressesremoises.fr\/#\/schema\/person\/23bf6fdaf1059471d3c6d236fdc5821e","name":"bonnesadressesremoises.fr"}]}},"_links":{"self":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/5580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5580"}],"version-history":[{"count":0,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/5580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/media\/9911"}],"wp:attachment":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}