{"id":8012,"date":"2015-02-15T11:04:55","date_gmt":"2015-02-15T09:04:55","guid":{"rendered":"http:\/\/bonnesadressesremoises.fr\/?p=8012"},"modified":"2015-04-18T12:16:06","modified_gmt":"2015-04-18T10:16:06","slug":"concours-champagne-bouc-lards-2015","status":"publish","type":"post","link":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/","title":{"rendered":"Jeu concours \u00ab\u00a0Bouc Lards\u00a0\u00bb"},"content":{"rendered":"<p>Nous sommes contents de poursuivre un projet sympathique pour nos lecteurs : proposer r\u00e9guli\u00e8rement des jeux concours sur notre site !<\/p>\n<p>Pour ce concours, un <strong>plateau de fromages<\/strong> \u00e0 gagner, pr\u00e9par\u00e9 par Samuel, de la tr\u00e8s bonne adresse du\u00a0<strong>\u00ab\u00a0Bouc Lards\u00a0\u00bb<\/strong> et \u00e0 venir retirer en boutique rue du Jard<em>\u00a0(d&rsquo;une valeur d&rsquo;environ 20\u20ac)<\/em>.<\/p>\n<p>Pour participer, il suffit de compl\u00e9ter le formulaire ci-dessous et de cliquer sur le bouton \u00ab\u00a0Valider\u00a0\u00bb avant le 14 mars 2015 inclus.<\/p>\n<p style=\"font-size: 12px;\">(une participation par foyer, jeu-concours r\u00e9serv\u00e9 aux habitants des d\u00e9partements 51, 52, 02, 08, 10)<\/p>\n<p><!--more--><\/p>\n<p><span style=\"color: #ff6600;\"><em>Jeu termin\u00e9 ! Le tirage au sort a d\u00e9sign\u00e9\u00a0<strong>Isabelle Depaix (51)<\/strong> comme l&rsquo;heureuse gagnante !<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes contents de poursuivre un projet sympathique pour nos lecteurs : proposer r\u00e9guli\u00e8rement des jeux concours sur notre site ! Pour ce concours, un plateau de fromages \u00e0 gagner, pr\u00e9par\u00e9 par Samuel, de la tr\u00e8s bonne adresse du\u00a0\u00ab\u00a0Bouc Lards\u00a0\u00bb &hellip; <a href=\"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110],"tags":[],"class_list":["post-8012","post","type-post","status-publish","format-standard","hentry","category-concours"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeu concours &quot;Bouc Lards&quot; # Bonnes Adresses R\u00e9moises<\/title>\n<meta name=\"description\" content=\"Nous sommes contents de poursuivre un projet sympathique pour nos lecteurs : proposer r\u00e9guli\u00e8rement des jeux concours sur notre site ! Pour ce concours,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"bonnesadressesremoises.fr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/\"},\"author\":{\"name\":\"bonnesadressesremoises.fr\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#\\\/schema\\\/person\\\/23bf6fdaf1059471d3c6d236fdc5821e\"},\"headline\":\"Jeu concours \u00ab\u00a0Bouc Lards\u00a0\u00bb\",\"datePublished\":\"2015-02-15T09:04:55+00:00\",\"dateModified\":\"2015-04-18T10:16:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/\"},\"wordCount\":105,\"commentCount\":0,\"articleSection\":[\"Concours\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/\",\"url\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/\",\"name\":\"Jeu concours \\\"Bouc Lards\\\" # Bonnes Adresses R\u00e9moises\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#website\"},\"datePublished\":\"2015-02-15T09:04:55+00:00\",\"dateModified\":\"2015-04-18T10:16:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#\\\/schema\\\/person\\\/23bf6fdaf1059471d3c6d236fdc5821e\"},\"description\":\"Nous sommes contents de poursuivre un projet sympathique pour nos lecteurs : proposer r\u00e9guli\u00e8rement des jeux concours sur notre site ! Pour ce concours,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/concours-champagne-bouc-lards-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concours\",\"item\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/index.php\\\/category\\\/concours\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jeu concours \u00ab\u00a0Bouc Lards\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#website\",\"url\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/\",\"name\":\"Bonnes Adresses R\u00e9moises\",\"description\":\"Des bonnes adresses sur Reims!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonnesadressesremoises.fr\\\/#\\\/schema\\\/person\\\/23bf6fdaf1059471d3c6d236fdc5821e\",\"name\":\"bonnesadressesremoises.fr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeu concours \"Bouc Lards\" # Bonnes Adresses R\u00e9moises","description":"Nous sommes contents de poursuivre un projet sympathique pour nos lecteurs : proposer r\u00e9guli\u00e8rement des jeux concours sur notre site ! Pour ce concours,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/","twitter_misc":{"\u00c9crit par":"bonnesadressesremoises.fr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/#article","isPartOf":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/"},"author":{"name":"bonnesadressesremoises.fr","@id":"https:\/\/bonnesadressesremoises.fr\/#\/schema\/person\/23bf6fdaf1059471d3c6d236fdc5821e"},"headline":"Jeu concours \u00ab\u00a0Bouc Lards\u00a0\u00bb","datePublished":"2015-02-15T09:04:55+00:00","dateModified":"2015-04-18T10:16:06+00:00","mainEntityOfPage":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/"},"wordCount":105,"commentCount":0,"articleSection":["Concours"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/","url":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/","name":"Jeu concours \"Bouc Lards\" # Bonnes Adresses R\u00e9moises","isPartOf":{"@id":"https:\/\/bonnesadressesremoises.fr\/#website"},"datePublished":"2015-02-15T09:04:55+00:00","dateModified":"2015-04-18T10:16:06+00:00","author":{"@id":"https:\/\/bonnesadressesremoises.fr\/#\/schema\/person\/23bf6fdaf1059471d3c6d236fdc5821e"},"description":"Nous sommes contents de poursuivre un projet sympathique pour nos lecteurs : proposer r\u00e9guli\u00e8rement des jeux concours sur notre site ! Pour ce concours,","breadcrumb":{"@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bonnesadressesremoises.fr\/index.php\/concours-champagne-bouc-lards-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bonnesadressesremoises.fr\/"},{"@type":"ListItem","position":2,"name":"Concours","item":"https:\/\/bonnesadressesremoises.fr\/index.php\/category\/concours\/"},{"@type":"ListItem","position":3,"name":"Jeu concours \u00ab\u00a0Bouc Lards\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/bonnesadressesremoises.fr\/#website","url":"https:\/\/bonnesadressesremoises.fr\/","name":"Bonnes Adresses R\u00e9moises","description":"Des bonnes adresses sur Reims!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonnesadressesremoises.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/bonnesadressesremoises.fr\/#\/schema\/person\/23bf6fdaf1059471d3c6d236fdc5821e","name":"bonnesadressesremoises.fr"}]}},"_links":{"self":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/8012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/comments?post=8012"}],"version-history":[{"count":0,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/posts\/8012\/revisions"}],"wp:attachment":[{"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/media?parent=8012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/categories?post=8012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonnesadressesremoises.fr\/index.php\/wp-json\/wp\/v2\/tags?post=8012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}